{"id":9,"date":"2019-01-03T14:51:40","date_gmt":"2019-01-03T14:51:40","guid":{"rendered":"https:\/\/demo.harutheme.com\/pangja\/?page_id=9"},"modified":"2019-01-03T14:51:40","modified_gmt":"2019-01-03T14:51:40","slug":"home-3","status":"publish","type":"page","link":"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/home-3\/","title":{"rendered":"Home 3"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_row_inner][vc_column_inner][rev_slider_vc alias=&#8221;home-3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1553065327931{padding-top: 6% !important;padding-bottom: 6% !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner]                        <div class=\" \">\n                <div class=\"clients-shortcode-wrap carousel \">\n    <div class=\"haru-carousel clients-list owl-carousel owl-theme\"\n        data-items=\"5\"\n        data-items-tablet=\"3\"\n        data-items-mobile=\"2\"\n        data-margin=\"20\"\n        data-autoplay=\"false\"\n        data-slide-duration=\"6000\"\n    >\n            \t<div class=\"client-item\">\n                <a href=\"#\" target=\"_self\">\n                    <img decoding=\"async\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/ms-black-1.png?ssl=1\" alt=\"MS\" data-recalc-dims=\"1\">\n                <\/a>\n                <\/div>\n            \t<div class=\"client-item\">\n                <a href=\"#\" target=\"_self\">\n                    <img decoding=\"async\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/wedding-black-1.png?ssl=1\" alt=\"Wedding\" data-recalc-dims=\"1\">\n                <\/a>\n                <\/div>\n            \t<div class=\"client-item\">\n                <a href=\"#\" target=\"_self\">\n                    <img decoding=\"async\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/holli-black-1.png?ssl=1\" alt=\"Holli\" data-recalc-dims=\"1\">\n                <\/a>\n                <\/div>\n            \t<div class=\"client-item\">\n                <a href=\"#\" target=\"_self\">\n                    <img decoding=\"async\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/hand-black-1.png?ssl=1\" alt=\"Hand\" data-recalc-dims=\"1\">\n                <\/a>\n                <\/div>\n            \t<div class=\"client-item\">\n                <a href=\"#\" target=\"_self\">\n                    <img decoding=\"async\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/pure-black-1.png?ssl=1\" alt=\"Pure\" data-recalc-dims=\"1\">\n                <\/a>\n                <\/div>\n            \t<div class=\"client-item\">\n                <a href=\"#\" target=\"_self\">\n                    <img decoding=\"async\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/holli-black-1.png?ssl=1\" alt=\"Holli\" data-recalc-dims=\"1\">\n                <\/a>\n                <\/div>\n            <\/div>\n<\/div>            <\/div>\n                    [\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1552373358581{padding-bottom: 4% !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner]                        <div class=\"  \">\n                <div class=\"banner-creative-shortcode-wrap packery \" \n    data-padding=\"10\"\n    data-columns=\"4\">\n    <div class=\"banner-content-wrap banner-list\">\n        \n        <div class=\"banner-item big_squared style_3 image-col-4 padding-10\">\n            <div class=\"banner-item-wrap\">\n                                    <a href=\"#\" class=\"banner-link\" target=\"_self\"><\/a>\n                                                    <img decoding=\"async\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/banner-21-1.jpg?ssl=1\" alt=\"\" data-recalc-dims=\"1\">\n                                <div class=\"banner-content-inner\">\n                    <div class=\"banner-content\">\n                                                                                    <h6 class=\"banner-title\">\n                                                                            <a href=\"#\" target=\"_self\">\n                                                                        Packing                                                                            <\/a>\n                                                                    <\/h6>\n                                                                                                                                <p class=\"banner-description\">23 items<\/p>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n        <div class=\"banner-item landscape style_3 image-col-4 padding-10\">\n            <div class=\"banner-item-wrap\">\n                                    <a href=\"#\" class=\"banner-link\" target=\"_self\"><\/a>\n                                                    <img decoding=\"async\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/banner-22-1.jpg?ssl=1\" alt=\"\" data-recalc-dims=\"1\">\n                                <div class=\"banner-content-inner\">\n                    <div class=\"banner-content\">\n                                                                                    <h6 class=\"banner-title\">\n                                                                            <a href=\"#\" target=\"_self\">\n                                                                        Invitations                                                                            <\/a>\n                                                                    <\/h6>\n                                                                                                                                                                        <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n        <div class=\"banner-item default style_3 image-col-4 padding-10\">\n            <div class=\"banner-item-wrap\">\n                                    <a href=\"#\" class=\"banner-link\" target=\"_self\"><\/a>\n                                                    <img decoding=\"async\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/banner-23-1.jpg?ssl=1\" alt=\"\" data-recalc-dims=\"1\">\n                                <div class=\"banner-content-inner\">\n                    <div class=\"banner-content\">\n                                                                                    <h6 class=\"banner-title\">\n                                                                            <a href=\"#\" target=\"_self\">\n                                                                        Wall Paper                                                                            <\/a>\n                                                                    <\/h6>\n                                                                                                                                                                        <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n        <div class=\"banner-item default style_3 image-col-4 padding-10\">\n            <div class=\"banner-item-wrap\">\n                                    <a href=\"#\" class=\"banner-link\" target=\"_self\"><\/a>\n                                                    <img decoding=\"async\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/banner-24-1.jpg?ssl=1\" alt=\"\" data-recalc-dims=\"1\">\n                                <div class=\"banner-content-inner\">\n                    <div class=\"banner-content\">\n                                                                                    <h6 class=\"banner-title\">\n                                                                            <a href=\"#\" target=\"_self\">\n                                                                        Kute Bags                                                                            <\/a>\n                                                                    <\/h6>\n                                                                                                                                                                        <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\n            <\/div>\n<\/div>            <\/div>\n                    [\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1548842599522{padding-bottom: 8% !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner el_class=&#8221;haru-col-sm-2&#8243; width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner el_class=&#8221;haru-col-sm-8&#8243; width=&#8221;1\/2&#8243;][vc_custom_heading heading_style=&#8221;heading_style_1&#8243; text=&#8221;Top Seller&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_column_text css=&#8221;.vc_custom_1548842565903{padding-top: 3% !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\">Lorem ipsum dolor sit amet, consectetur adipiscing elit duis nec fringilla nibh pellentesque finibus<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;haru-col-sm-2&#8243; width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][haru_products columns=&#8221;4&#8243; filter_style=&#8221;style_1&#8243; paging_style=&#8221;load-more&#8221; per_page=&#8221;8&#8243; category=&#8221;business-cards,calendars,cateloge,decoration,invitations&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; equal_height=&#8221;yes&#8221;][vc_column width=&#8221;7\/12&#8243; css=&#8221;.vc_custom_1552378434086{background-image: url(https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/video-bg-6-1.jpg?id=295) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;video-home-6 overlay-background-column&#8221;][vc_row_inner][vc_column_inner]                    <div class=\"  \">\n                <div class=\"video-shortcode-wrap style_1 \">\n    <div class=\"video-shortcode-content\">\n        <div class=\"video-button\">\n            <a class=\"video-popup-link\" title=\"\" href=\"https:\/\/www.youtube.com\/watch?v=v94zxzMZ6b4\"><i class=\"simpline icon-control-play\"><\/i><\/a>\n        <\/div>\n    <\/div>\n<\/div>            <\/div>\n                [\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;5\/12&#8243; css=&#8221;.vc_custom_1552378460719{background-color: #f9f9f9 !important;}&#8221;][vc_row_inner el_class=&#8221;testimonial-3&#8243;][vc_column_inner]        \n        <div class=\" \">\n            <div class=\"testimonial-shortcode-wrap carousel_4 \">\n    <div class=\"haru-carousel testimonial-list owl-carousel owl-theme\"\n        data-items=\"1\"\n        data-items-tablet=\"1\"\n        data-items-mobile=\"1\"\n        data-margin=\"20\"\n        data-loop=\"true\"\n        data-autoplay=\"true\"\n        data-slide-duration=\"6000\">\n                <div class=\"testimonial-item\">\n            <div class=\"testimonial-top\">\n                <div class=\"testimonial-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/testimonial-1-1.jpg?resize=60%2C60&#038;ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" data-recalc-dims=\"1\" \/>                <\/div>\n                <div class=\"testimonial-author-meta\">\n                    <span class=\"testimonial-title\">Alan Spider<\/span>\n                                        <span class=\"testimonial-position\">CEO<\/span>\n                                    <\/div>\n            <\/div>\n            <div class=\"text-testimonial\">Pellentesque maximus erat a eros finibus scelerisque. Nullam dictum, elit quis finibus venenatis, sem lacus lobortis enim, vel molestie velit justo eget ex. Proin pharetra arcu sit amet mollis efficitur. Cras volutpat leo a accumsan diam pellentesque, sit amet molestie augue malesuada. Suspendisse sagittis varius purus, at tincidunt orci. <\/div>\n                        <div class=\"testimonial-rating\">\n                                <span class=\"ion-ios-star\"><\/span>\n                                <span class=\"ion-ios-star\"><\/span>\n                                <span class=\"ion-ios-star\"><\/span>\n                                <span class=\"ion-ios-star\"><\/span>\n                                <span class=\"ion-ios-star\"><\/span>\n                            <\/div>\n                    <\/div>\n                <div class=\"testimonial-item\">\n            <div class=\"testimonial-top\">\n                <div class=\"testimonial-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/testimonial-1-1.jpg?resize=60%2C60&#038;ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" data-recalc-dims=\"1\" \/>                <\/div>\n                <div class=\"testimonial-author-meta\">\n                    <span class=\"testimonial-title\">Mary Lous<\/span>\n                                        <span class=\"testimonial-position\">Designer<\/span>\n                                    <\/div>\n            <\/div>\n            <div class=\"text-testimonial\">Pellentesque maximus erat a eros finibus scelerisque. Nullam dictum, elit quis finibus venenatis, sem lacus lobortis enim, vel molestie velit justo eget ex. Proin pharetra arcu sit amet mollis efficitur. Cras volutpat leo a accumsan diam pellentesque, sit amet molestie augue malesuada. Suspendisse sagittis varius purus, at tincidunt orci. <\/div>\n                        <div class=\"testimonial-rating\">\n                                <span class=\"ion-ios-star\"><\/span>\n                                <span class=\"ion-ios-star\"><\/span>\n                                <span class=\"ion-ios-star\"><\/span>\n                                <span class=\"ion-ios-star\"><\/span>\n                                <span class=\"ion-ios-star\"><\/span>\n                            <\/div>\n                    <\/div>\n                <div class=\"testimonial-item\">\n            <div class=\"testimonial-top\">\n                <div class=\"testimonial-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/testimonial-1-1.jpg?resize=60%2C60&#038;ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" data-recalc-dims=\"1\" \/>                <\/div>\n                <div class=\"testimonial-author-meta\">\n                    <span class=\"testimonial-title\">Jenny Parker<\/span>\n                                        <span class=\"testimonial-position\">Marketing<\/span>\n                                    <\/div>\n            <\/div>\n            <div class=\"text-testimonial\">Pellentesque maximus erat a eros finibus scelerisque. Nullam dictum, elit quis finibus venenatis, sem lacus lobortis enim, vel molestie velit justo eget ex. Proin pharetra arcu sit amet mollis efficitur. Cras volutpat leo a accumsan diam pellentesque, sit amet molestie augue malesuada. Suspendisse sagittis varius purus, at tincidunt orci. <\/div>\n                        <div class=\"testimonial-rating\">\n                                <span class=\"ion-ios-star\"><\/span>\n                                <span class=\"ion-ios-star\"><\/span>\n                                <span class=\"ion-ios-star\"><\/span>\n                                <span class=\"ion-ios-star\"><\/span>\n                                <span class=\"ion-ios-star\"><\/span>\n                            <\/div>\n                    <\/div>\n            <\/div>\n<\/div>        <\/div>  \n        \n        [\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1551342595722{padding-top: 5% !important;padding-bottom: 8% !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner el_class=&#8221;haru-col-sm-2&#8243; width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner el_class=&#8221;haru-col-sm-8&#8243; width=&#8221;1\/2&#8243;][vc_custom_heading heading_style=&#8221;heading_style_4&#8243; text=&#8221;Latest News&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_column_text css=&#8221;.vc_custom_1548842727629{padding-top: 3% !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\">Lorem ipsum dolor sit amet, consectetur adipiscing elit duis nec fringilla nibh pellentesque finibus<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;haru-col-sm-2&#8243; width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;2\/3&#8243;]  \n        <div class=\" \">\n                <div class=\"recent-news-shortcode-wrap carousel_3 \">\n        <div class=\"haru-carousel recent-news-container owl-carousel owl-theme\"\n            data-items=\"2\"\n            data-items-desktop=\"2\"\n            data-items-tablet=\"2\"\n            data-items-mobile=\"1\"\n            data-margin=\"30\"\n            data-autoplay=\"false\"\n            data-slide-duration=\"6000\"\n        >\n                                    <div class=\"recent-news-item-wrap\">\n                <article class=\"recent-news-item\">\n                    <div class=\"post-thumbnail\">\n                        <a class=\"post-thumbnail-link\" href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/a-study-in-street-style\/\"><\/a>\n                        <div class=\"post-image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"848\" height=\"400\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/single-blog-1-1.jpg?resize=848%2C400&#038;ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/single-blog-1-1.jpg?w=848&amp;ssl=1 848w, https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/single-blog-1-1.jpg?resize=300%2C142&amp;ssl=1 300w, https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/single-blog-1-1.jpg?resize=768%2C362&amp;ssl=1 768w\" sizes=\"auto, (max-width: 848px) 100vw, 848px\" data-recalc-dims=\"1\" \/>                        <\/div>\n                        <div class=\"post-category\">\n                                                            <a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/category\/calendars\/\" rel=\"category tag\">Calendars<\/a>                                                    <\/div>\n                    <\/div>\n                    <div class=\"post-content d-flex\">\n                        <div class=\"post-meta-date\">\n                            <div class=\"post-day\">24<\/div>\n                            <div class=\"post-month\">Dez.<\/div>\n                        <\/div>\n                        <div class=\"post-content-wrap\">\n                            <div class=\"post-meta\">\n                                <div class=\"post-meta-views\"><i class=\"icon-eye\"><\/i>109 Views<\/div>\n                                <div class=\"post-meta-comment\">\n                                    <i class=\"fa fa-comments-o\"><\/i>\n                                    <a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/a-study-in-street-style\/#comments\">6 Comments<\/a>                                <\/div>\n                            <\/div>\n                            <h3 class=\"entry-title\"><a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/a-study-in-street-style\/\">A Study In Street Style<\/a><\/h3>\n                            <div class=\"post-excerpt\">\n                                ...                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/article>\n            <\/div>\n                                    <div class=\"recent-news-item-wrap\">\n                <article class=\"recent-news-item\">\n                    <div class=\"post-thumbnail\">\n                        <a class=\"post-thumbnail-link\" href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/ut-wisi-enim-ad-minim-veniam\/\"><\/a>\n                        <div class=\"post-image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"848\" height=\"400\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/single-blog-1-1.jpg?resize=848%2C400&#038;ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/single-blog-1-1.jpg?w=848&amp;ssl=1 848w, https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/single-blog-1-1.jpg?resize=300%2C142&amp;ssl=1 300w, https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/single-blog-1-1.jpg?resize=768%2C362&amp;ssl=1 768w\" sizes=\"auto, (max-width: 848px) 100vw, 848px\" data-recalc-dims=\"1\" \/>                        <\/div>\n                        <div class=\"post-category\">\n                                                            <a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/category\/indoor-signage\/\" rel=\"category tag\">Indoor Signage<\/a>                                                    <\/div>\n                    <\/div>\n                    <div class=\"post-content d-flex\">\n                        <div class=\"post-meta-date\">\n                            <div class=\"post-day\">24<\/div>\n                            <div class=\"post-month\">Dez.<\/div>\n                        <\/div>\n                        <div class=\"post-content-wrap\">\n                            <div class=\"post-meta\">\n                                <div class=\"post-meta-views\"><i class=\"icon-eye\"><\/i>99 Views<\/div>\n                                <div class=\"post-meta-comment\">\n                                    <i class=\"fa fa-comments-o\"><\/i>\n                                    <a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/ut-wisi-enim-ad-minim-veniam\/#comments\">6 Comments<\/a>                                <\/div>\n                            <\/div>\n                            <h3 class=\"entry-title\"><a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/ut-wisi-enim-ad-minim-veniam\/\">Ut wisi enim ad minim veniam<\/a><\/h3>\n                            <div class=\"post-excerpt\">\n                                ...                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/article>\n            <\/div>\n                                    <div class=\"recent-news-item-wrap\">\n                <article class=\"recent-news-item\">\n                    <div class=\"post-thumbnail\">\n                        <a class=\"post-thumbnail-link\" href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/eodem-modo-typi-qui-nunc-nobis-videntur-parum-clari\/\"><\/a>\n                        <div class=\"post-image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"848\" height=\"400\" src=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/single-blog-1-1.jpg?resize=848%2C400&#038;ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/single-blog-1-1.jpg?w=848&amp;ssl=1 848w, https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/single-blog-1-1.jpg?resize=300%2C142&amp;ssl=1 300w, https:\/\/i0.wp.com\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/single-blog-1-1.jpg?resize=768%2C362&amp;ssl=1 768w\" sizes=\"auto, (max-width: 848px) 100vw, 848px\" data-recalc-dims=\"1\" \/>                        <\/div>\n                        <div class=\"post-category\">\n                                                            <a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/category\/calendars\/\" rel=\"category tag\">Calendars<\/a>, <a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/category\/invitations\/\" rel=\"category tag\">Invitations<\/a>                                                    <\/div>\n                    <\/div>\n                    <div class=\"post-content d-flex\">\n                        <div class=\"post-meta-date\">\n                            <div class=\"post-day\">24<\/div>\n                            <div class=\"post-month\">Dez.<\/div>\n                        <\/div>\n                        <div class=\"post-content-wrap\">\n                            <div class=\"post-meta\">\n                                <div class=\"post-meta-views\"><i class=\"icon-eye\"><\/i>108 Views<\/div>\n                                <div class=\"post-meta-comment\">\n                                    <i class=\"fa fa-comments-o\"><\/i>\n                                    <a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/eodem-modo-typi-qui-nunc-nobis-videntur-parum-clari\/#comments\">6 Comments<\/a>                                <\/div>\n                            <\/div>\n                            <h3 class=\"entry-title\"><a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/eodem-modo-typi-qui-nunc-nobis-videntur-parum-clari\/\">Eodem modo typi, qui nunc nobis videntur parum clari<\/a><\/h3>\n                            <div class=\"post-excerpt\">\n                                ...                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/article>\n            <\/div>\n                    <\/div>\n    <\/div>\n        <\/div>\n        [\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]  \n        <div class=\" \">\n                <div class=\"recent-news-shortcode-wrap list \">\n        <div class=\"recent-news-container\" >\n                        <article class=\"recent-news-item\">\n                <div class=\"post-left\">\n                    <div class=\"post-meta-date\">\n                        <div class=\"post-day\">24<\/div>\n                        <div class=\"post-month\">Dez.<\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"post-content\">\n                    <div class=\"post-meta\">\n                        <div class=\"post-meta-views\"><i class=\"icon-eye\"><\/i>109 Views<\/div>\n                        <div class=\"post-meta-comment\">\n                            <i class=\"fa fa-comments-o\"><\/i>\n                            <a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/a-study-in-street-style\/#comments\">6 Comments<\/a>                        <\/div>\n                    <\/div>\n                    <h3 class=\"entry-title\"><a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/a-study-in-street-style\/\">A Study In Street Style<\/a><\/h3>\n                <\/div>\n            <\/article>\n                        <article class=\"recent-news-item\">\n                <div class=\"post-left\">\n                    <div class=\"post-meta-date\">\n                        <div class=\"post-day\">24<\/div>\n                        <div class=\"post-month\">Dez.<\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"post-content\">\n                    <div class=\"post-meta\">\n                        <div class=\"post-meta-views\"><i class=\"icon-eye\"><\/i>99 Views<\/div>\n                        <div class=\"post-meta-comment\">\n                            <i class=\"fa fa-comments-o\"><\/i>\n                            <a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/ut-wisi-enim-ad-minim-veniam\/#comments\">6 Comments<\/a>                        <\/div>\n                    <\/div>\n                    <h3 class=\"entry-title\"><a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/ut-wisi-enim-ad-minim-veniam\/\">Ut wisi enim ad minim veniam<\/a><\/h3>\n                <\/div>\n            <\/article>\n                        <article class=\"recent-news-item\">\n                <div class=\"post-left\">\n                    <div class=\"post-meta-date\">\n                        <div class=\"post-day\">24<\/div>\n                        <div class=\"post-month\">Dez.<\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"post-content\">\n                    <div class=\"post-meta\">\n                        <div class=\"post-meta-views\"><i class=\"icon-eye\"><\/i>108 Views<\/div>\n                        <div class=\"post-meta-comment\">\n                            <i class=\"fa fa-comments-o\"><\/i>\n                            <a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/eodem-modo-typi-qui-nunc-nobis-videntur-parum-clari\/#comments\">6 Comments<\/a>                        <\/div>\n                    <\/div>\n                    <h3 class=\"entry-title\"><a href=\"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/2021\/12\/24\/eodem-modo-typi-qui-nunc-nobis-videntur-parum-clari\/\">Eodem modo typi, qui nunc nobis videntur parum clari<\/a><\/h3>\n                <\/div>\n            <\/article>\n                    <\/div>\n    <\/div>\n        <\/div>\n        [\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_row_inner][vc_column_inner][rev_slider_vc alias=&#8221;home-3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1553065327931{padding-top: 6% !important;padding-bottom: 6% !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; css=&#8221;.vc_custom_1552373358581{padding-bottom: 4% !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1548842599522{padding-bottom: 8% !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner el_class=&#8221;haru-col-sm-2&#8243; width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner el_class=&#8221;haru-col-sm-8&#8243; width=&#8221;1\/2&#8243;][vc_custom_heading heading_style=&#8221;heading_style_1&#8243; text=&#8221;Top Seller&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_column_text css=&#8221;.vc_custom_1548842565903{padding-top: 3% !important;}&#8221;] Lorem ipsum dolor sit amet, consectetur adipiscing elit duis nec fringilla nibh pellentesque finibus [\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;haru-col-sm-2&#8243; width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][haru_products columns=&#8221;4&#8243; filter_style=&#8221;style_1&#8243; paging_style=&#8221;load-more&#8221; per_page=&#8221;8&#8243; category=&#8221;business-cards,calendars,cateloge,decoration,invitations&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; equal_height=&#8221;yes&#8221;][vc_column width=&#8221;7\/12&#8243; css=&#8221;.vc_custom_1552378434086{background-image: url(https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/wp-content\/uploads\/2019\/01\/video-bg-6-1.jpg?id=295) !important;background-position: center [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry","clearfix"],"_links":{"self":[{"href":"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":0,"href":"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"wp:attachment":[{"href":"https:\/\/unruffled-matsumoto.5-9-23-233.plesk.page\/index.php\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}